{"id":1499,"date":"2020-11-23T05:20:58","date_gmt":"2020-11-23T05:20:58","guid":{"rendered":"https:\/\/invezt.co\/kaymera\/?p=1499"},"modified":"2020-11-23T05:20:58","modified_gmt":"2020-11-23T05:20:58","slug":"estafa-global-compromete-mas-de-100000-cuentas-de-facebook","status":"publish","type":"post","link":"https:\/\/unicode7.com\/index.php\/2020\/11\/23\/estafa-global-compromete-mas-de-100000-cuentas-de-facebook\/","title":{"rendered":"Estafa global compromete m\u00e1s de 100,000 cuentas de Facebook"},"content":{"rendered":"\n<p>Seg\u00fan informaci\u00f3n de la empresa especializada en ciberseguridad <a href=\"https:\/\/www.eset.com\/mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">Eset<\/a>, una base de datos del buscador\u00a0<strong><a href=\"https:\/\/www.elastic.co\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Elasticsearch<\/a>\u00a0<\/strong>indebidamente configurada y operada por <strong><a href=\"https:\/\/invezt.co\/kaymera\/es\/amenazas\/\" target=\"_blank\" rel=\"noreferrer noopener\">ciberdelincuentes<\/a><\/strong>\u00a0expuso nombres de usuario y contrase\u00f1as de m\u00e1s de 100.000\u00a0cuentas de\u00a0Facebook. <\/p>\n\n\n\n<p>La vulneraci\u00f3n descubri\u00f3 una campa\u00f1a de enga\u00f1o a usuarios de Facebook. Al vincular sus cuentas a una herramienta que\u00a0<strong>supuestamente revelaba qui\u00e9n hab\u00eda visto su perfil, su objetivo final era robar sus credenciales.<\/strong><\/p>\n\n\n\n<p>No se sabe exactamente c\u00f3mo llegan las v\u00edctimas a estos sitios falsos que prometen revelar quienes visitaron su perfil de Facebook pero se relacion\u00f3 a <strong>29 dominios<\/strong>. Estos sitios inclu\u00edan, por ejemplo, mensajes como \u201cTu perfil recibi\u00f3 32 visitas en los \u00faltimos dos d\u00edas. Contin\u00faa para ver la lista\u201d. Si la v\u00edctima hac\u00eda clic en un bot\u00f3n \u201cabrir la lista\u201d ser\u00eda dirigida a una falsa p\u00e1gina de inicio de sesi\u00f3n de Facebook y se solicitar\u00eda que ingrese sus credenciales de acceso a la plataforma.<\/p>\n\n\n\n<p>Las credenciales se almacenan en la base de datos controlada por los atacantes para luego comenzar con la otra fase de la campa\u00f1a maliciosa. Los comentarios en las cuentas de las v\u00edctimas que contienen enlaces a sitios que forman parte de un esquema fraudulento operado por los cibercriminales.<\/p>\n\n\n\n<p>La red de sitios es una estrategia para<strong>\u00a0<\/strong>evadir los mecanismos de detecci\u00f3n y evitar ser bloqueados, seg\u00fan Eset, el principal objetivo era dirigir a las v\u00edctimas a sitios en los que se invitaba a registrarse para acceder a una\u00a0<strong>cuenta gratuita\u00a0<\/strong>de trading de\u00a0<strong>Bitcoin\u00a0<\/strong>y depositar\u00a0<strong>250 euros<\/strong>. En caso de realizar el dep\u00f3sito, el dinero iba a parar a manos de los cibercriminales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Datos almacenados de las cuentas de Facebook<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>Nombres de usuario y contrase\u00f1as de entre 150.000 y 200.000 cuentas de Facebook, adem\u00e1s de direcciones IP.<\/li><li>Informaci\u00f3n de identificaci\u00f3n personal (PII) de v\u00edctimas, como direcci\u00f3n de correo, nombres, o n\u00fameros de tel\u00e9fono.<\/li><li>Textos utilizados por los estafadores al momento de publicar comentarios en las cuentas comprometidas para dirigir a las v\u00edctimas a sitios maliciosos.<\/li><\/ol>\n\n\n\n<p>\u201c<strong>Aprovechamos para recomendar a los usuarios no utilizar la misma contrase\u00f1a en m\u00e1s de un servicio<\/strong>. Para evitar dolores de cabeza teniendo que recordar cada una de las contrase\u00f1as utilizadas en cada cuentas o servicios, recomendamos utilizar un\u00a0<strong>gestor de contrase\u00f1as<\/strong>\u201d, dice Camilo Guti\u00e9rrez Amaya, Jefe del Laboratorio de Investigaci\u00f3n de ESET Latinoam\u00e9rica.<\/p>\n\n\n\n<p>Con informaci\u00f3n de infobae.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan informaci\u00f3n de la empresa especializada en ciberseguridad Eset, una base de datos del buscador\u00a0Elasticsearch\u00a0indebidamente configurada y operada por ciberdelincuentes\u00a0expuso nombres de usuario y contrase\u00f1as de m\u00e1s de 100.000\u00a0cuentas de\u00a0Facebook. La vulneraci\u00f3n descubri\u00f3 una campa\u00f1a de enga\u00f1o a usuarios de Facebook. Al vincular sus cuentas a una herramienta que\u00a0supuestamente revelaba qui\u00e9n hab\u00eda visto su perfil,&hellip;&nbsp;<a href=\"https:\/\/unicode7.com\/index.php\/2020\/11\/23\/estafa-global-compromete-mas-de-100000-cuentas-de-facebook\/\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">Estafa global compromete m\u00e1s de 100,000 cuentas de Facebook<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1500,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[6],"tags":[124,125,126,11,12,13,127],"class_list":["post-1499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-ciberdelincuencia","tag-cuentas-de-facebook","tag-elasticsearch","tag-kaymera","tag-kaymera-app","tag-kaymera-technologies","tag-usuario-y-contrasena"],"_links":{"self":[{"href":"https:\/\/unicode7.com\/index.php\/wp-json\/wp\/v2\/posts\/1499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unicode7.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unicode7.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unicode7.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unicode7.com\/index.php\/wp-json\/wp\/v2\/comments?post=1499"}],"version-history":[{"count":0,"href":"https:\/\/unicode7.com\/index.php\/wp-json\/wp\/v2\/posts\/1499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unicode7.com\/index.php\/wp-json\/wp\/v2\/media\/1500"}],"wp:attachment":[{"href":"https:\/\/unicode7.com\/index.php\/wp-json\/wp\/v2\/media?parent=1499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unicode7.com\/index.php\/wp-json\/wp\/v2\/categories?post=1499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unicode7.com\/index.php\/wp-json\/wp\/v2\/tags?post=1499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}